{"id":35063,"date":"2023-07-29T07:58:00","date_gmt":"2023-07-29T05:58:00","guid":{"rendered":"https:\/\/www.art-lempreinte.ch\/?post_type=product&#038;p=35063"},"modified":"2025-08-17T08:06:45","modified_gmt":"2025-08-17T06:06:45","slug":"symphonie-des-couleurs","status":"publish","type":"product","link":"https:\/\/www.art-lempreinte.ch\/en\/tableaux\/symphonie-des-couleurs\/","title":{"rendered":"Symphonie des couleurs"},"content":{"rendered":"<p><strong>Livraison:<\/strong><\/p>\n<p>Suisse: 29 CHF<\/p>\n<p>Europe: 59 CHF<\/p>\n<p>Pour une livraison par la poste, cette dimension est consid\u00e9r\u00e9e comme &#8220;encombrant&#8221;, merci de vous r\u00e9f\u00e9rez aux conditions g\u00e9n\u00e9rales de vente.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div id=\"short_description_block\">\n<div id=\"short_description_content\" class=\"rte align_justify\">\n<p>Dimension : 120 x 80 cm<\/p>\n<p>Peinture abstraite, acrylique, ch\u00e2ssis en bois sur toile en coton<\/p>\n<p>J\u2019ai r\u00e9alis\u00e9 ce tableau dans un choix de couleurs vari\u00e9es, un style moderne et original, une toile unique, peinte \u00e0 la main et tr\u00e8s color\u00e9es.<\/p>\n<p>Les bords du tableau sont peints et non clout\u00e9s afin que le tableau puisse directement \u00eatre mis au mur sans encadrement.<\/p>\n<p>Cl\u00e9s de ch\u00e2ssis d\u00e9j\u00e0 install\u00e9es, vous permettra d\u2019avoir un beau ch\u00e2ssis robuste qui vieillira dans de bonnes conditions.<\/p>\n<p>Au dos du tableau\u00a0: sont petit nom, sa date de cr\u00e9ation et ma signature.<\/p>\n<p>Fourni avec le tableau\u00a0: un certificat d\u2019authenticit\u00e9 ainsi qu\u2019une facture d\u00e9taill\u00e9e.<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":35084,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[73],"product_tag":[],"class_list":["post-35063","product","type-product","status-publish","has-post-thumbnail","product_cat-tableaux-a-vendre","pa_couleur-bleu","pa_couleur-brun","pa_couleur-dore","pa_couleur-jaune","pa_couleur-noir","pa_couleur-orange","pa_couleur-violet","first","instock","sale","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/product\/35063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/comments?post=35063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/media\/35084"}],"wp:attachment":[{"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/media?parent=35063"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/product_brand?post=35063"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/product_cat?post=35063"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.art-lempreinte.ch\/en\/wp-json\/wp\/v2\/product_tag?post=35063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}